{"id":2765548,"date":"2024-05-31T11:26:10","date_gmt":"2024-05-31T11:26:10","guid":{"rendered":""},"modified":"2026-01-22T15:43:03","modified_gmt":"2026-01-22T13:43:03","slug":"kulma-portsjoni-kausikesed-pla-90-ml-pakis-100-tk","status":"publish","type":"product","link":"https:\/\/mixpack.ee\/ru\/product\/kulma-portsjoni-kausikesed-pla-90-ml-pakis-100-tk\/","title":{"rendered":"\u0421\u043e\u0443\u0441\u043d\u0438\u0446\u0430 \u0434\u043b\u044f \u0445\u043e\u043b\u043e\u0434\u043d\u043e\u0433\u043e \u0438\u0437 \u043a\u0443\u043a\u0443\u0440\u0443\u0437\u043d\u043e\u0433\u043e \u043a\u0440\u0430\u0445\u043c\u0430\u043b\u0430, 90 \u043c\u043b, \u0432 \u043f\u0430\u0447\u043a\u0435 100 \u0448\u0442"},"content":{"rendered":"<p><TABLE> <TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0420\u0430\u0437\u043c\u0435\u0440<\/TD><br \/>\n<TD class='ss_at_val'>90 ml<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u041a\u043e\u043b-\u0432\u043e \u0448\u0442\u0443\u043a \u0432 \u043f\u0430\u0447\u043a\u0435<\/TD><br \/>\n<TD class='ss_at_val'>100<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>EAN<\/TD><br \/>\n<TD class='ss_at_val'>5060271922116<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u041a\u043e\u043b-\u0432\u043e \u043f\u0430\u0447\u0435\u043a \u0432 \u043a\u043e\u0440\u043e\u0431\u043a\u0435<\/TD><br \/>\n<TD class='ss_at_val'>20<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u041a\u043e\u043b-\u0432\u043e \u0448\u0442\u0443\u043a \u0432 \u043a\u043e\u0440\u043e\u0431\u043a\u0435<\/TD><br \/>\n<TD class='ss_at_val'>2000<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0414\u043b\u0438\u043d\u0430 \u043a\u043e\u0440\u043e\u0431\u043a\u0438 (\u043c)<\/TD><br \/>\n<TD class='ss_at_val'>0,36<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0412\u044b\u0441\u043e\u0442\u0430 \u043a\u043e\u0440\u043e\u0431\u043a\u0438 (\u043c)<\/TD><br \/>\n<TD class='ss_at_val'>0,285<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0413\u043b\u0443\u0431\u0438\u043d\u0430 \u043a\u043e\u0440\u043e\u0431\u043a\u0438 (\u043c)<\/TD><br \/>\n<TD class='ss_at_val'>0,3<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u041e\u0431\u044a\u0435\u043c \u043a\u043e\u0440\u043e\u0431\u043a\u0438 (\u043c3)<\/TD><br \/>\n<TD class='ss_at_val'>0,031<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>1.7\u043c \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u043d\u0430 \u043f\u0430\u043b\u0435\u0442\u0435<\/TD><br \/>\n<TD class='ss_at_val'>54<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>2.1\u043c \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u043d\u0430 \u043f\u0430\u043b\u0435\u0442\u0435<\/TD><br \/>\n<TD class='ss_at_val'>54<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0412\u0435\u0441 \u0442\u043e\u0432\u0430\u0440\u0430 \u043d\u0435\u0442\u0442\u043e (\u043a\u0433)<\/TD><br \/>\n<TD class='ss_at_val'>5,4<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0412\u0435\u0441 \u0442\u043e\u0432\u0430\u0440\u0430 \u0431\u0440\u0443\u0442\u0442\u043e (\u043a\u0433)<\/TD><br \/>\n<TD class='ss_at_val'>6,5<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0412\u0435\u0441 \u0432\u043d\u0435\u0448\u043d\u0435\u0439 \u0443\u043f\u0430\u043a\u043e\u0432\u043a\u0438 (\u043a\u0433)<\/TD><br \/>\n<TD class='ss_at_val'>1<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0412\u0435\u0441 \u0432\u043d\u0443\u0442\u0440\u0435\u043d\u043d\u0435\u0439 \u0443\u043f\u0430\u043a\u043e\u0432\u043a\u0438 (\u043a\u0433)<\/TD><br \/>\n<TD class='ss_at_val'>0,1<\/TD><br \/>\n<\/TR><br \/>\n<TR class='ss_at'><br \/>\n<TD class='ss_at_name'>\u0412\u0435\u0441 \u043f\u0430\u0447\u043a\u0438 (\u043a\u0433)<\/TD><br \/>\n<TD class='ss_at_val'>0,27<\/TD><br \/>\n<\/TR><br \/>\n<\/TABLE>ss_serdce=1;ss_treug=0;ss_elka=0;ss_petla=1;ss_carbon=1;ss_piece_count=100 ;ss_korobka_count=20 ;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u041d\u0430\u0448\u0438 90-\u043c\u0438\u043b\u043b\u0438\u043b\u0438\u0442\u0440\u043e\u0432\u044b\u0435 \u0441\u043e\u0443\u0441\u043d\u0438\u0446\u044b &#8211; \u043f\u0440\u0435\u0432\u043e\u0441\u0445\u043e\u0434\u043d\u043e\u0435 \u0440\u0435\u0448\u0435\u043d\u0438\u0435 \u0434\u043b\u044f \u043d\u0435\u0431\u043e\u043b\u044c\u0448\u0438\u0445 \u043f\u043e\u0440\u0446\u0438\u0439 \u0438 \u0436\u0438\u0434\u043a\u043e\u0441\u0442\u0435\u0439. \u041e\u043d\u0438 \u043c\u043e\u0433\u0443\u0442 \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u0442\u044c\u0441\u044f \u0434\u043b\u044f \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u0438\u044f \u043e\u0431\u0440\u0430\u0437\u0446\u043e\u0432 \u0438\u043b\u0438 \u0434\u043b\u044f \u043f\u043e\u0434\u0430\u0447\u0438 \u0441\u043e\u0443\u0441\u043e\u0432 \u0438 \u0437\u0430\u043a\u0443\u0441\u043e\u043a, \u0430 \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u044b\u0435 \u043a\u0440\u044b\u0448\u043a\u0438 (\u043f\u0440\u043e\u0434\u0430\u044e\u0442\u0441\u044f \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u043e) \u043f\u043e\u043c\u043e\u0433\u0443\u0442 \u043f\u0440\u0435\u0434\u043e\u0442\u0432\u0440\u0430\u0442\u0438\u0442\u044c \u043b\u044e\u0431\u043e\u0435 \u043f\u0440\u043e\u043b\u0438\u0432\u0430\u043d\u0438\u0435.\u0422\u0430\u043a\u0436\u0435 \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u043d\u0430\u0448\u0438\u0445 \u0442\u043e\u043d\u043a\u0438\u0445 \u0447\u0430\u0448\u0435\u043a \u043a\u0430\u043a \u0432\u0441\u0442\u0430\u0432\u043a\u0430 \u0434\u043b\u044f \u0445\u043b\u043e\u043f\u044c\u0435\u0432 \u0438 \u0439\u043e\u0433\u0443\u0440\u0442\u0430.<DIV class='hide'>5060271922116 CF7056<\/DIV><\/p>\n","protected":false},"featured_media":2765549,"template":"","meta":[],"product_brand":[],"product_cat":[7020,7019,7153,4662],"product_tag":[],"class_list":{"0":"post-2765548","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-degusteerimistops","7":"product_cat-topsid1","8":"product_cat-vaikesed-topsid","9":"product_cat-kastmetopsid","10":"product_shipping_class-mix","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mixpack.ee\/ru\/wp-json\/wp\/v2\/product\/2765548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mixpack.ee\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mixpack.ee\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mixpack.ee\/ru\/wp-json\/wp\/v2\/media\/2765549"}],"wp:attachment":[{"href":"https:\/\/mixpack.ee\/ru\/wp-json\/wp\/v2\/media?parent=2765548"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mixpack.ee\/ru\/wp-json\/wp\/v2\/product_brand?post=2765548"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mixpack.ee\/ru\/wp-json\/wp\/v2\/product_cat?post=2765548"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mixpack.ee\/ru\/wp-json\/wp\/v2\/product_tag?post=2765548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}